{"id":41643,"date":"2025-11-26T14:31:59","date_gmt":"2025-11-26T13:31:59","guid":{"rendered":"https:\/\/www.dbi-services.com\/blog\/?p=41643"},"modified":"2025-11-26T09:33:30","modified_gmt":"2025-11-26T08:33:30","slug":"benachrichtigungendefinition-in-m-files","status":"publish","type":"post","link":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/","title":{"rendered":"Benachrichtigungen in M-Files"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-was-sind-benachrichtigungen-in-m-files\">Was sind Benachrichtigungen in M-Files<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In <a href=\"https:\/\/www.m-files.com\" target=\"_blank\" rel=\"noreferrer noopener\">M-Files<\/a> besteht die M\u00f6glichkeit, Benachrichtigungen, sogenannte Zuweisungen, auf Basis von Ereignissen zu automatisieren. Die M-Files Benutzer werden zum einen direkt in M-Files mittels Zuweisungen informiert und zum anderen per E-Mail.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derzeit wird empfohlen, die Benachrichtigungsregeln mit dem klassischen M-Files-Client zu konfigurieren, da dieser die detailliertesten Konfigurationsm\u00f6glichkeiten bietet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-benachrichtigungen-erstellen\">Benachrichtigungen erstellen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Konfiguration kann durch Klicken auf den Benutzernamen in der rechten Ecke aufgerufen werden.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"451\" height=\"216\" src=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-13.png\" alt=\"\" class=\"wp-image-41646\" srcset=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-13.png 451w, https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-13-300x144.png 300w\" sizes=\"auto, (max-width: 451px) 100vw, 451px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Im Benachrichtigungsfenster haben Sie einen \u00dcberblick \u00fcber die konfigurierten Benachrichtigungen und haben auch die M\u00f6glichkeit, diese zu bearbeiten oder Neue zu erstellen.<br>Es gibt zwei Arten von Benachrichtigungen: &#8220;Sofort&#8221; oder &#8220;Einmal pro Tag&#8221;. Dies ist am Punkt &#8220;Nachrichtenszustellung&#8221; erkennbar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"318\" height=\"218\" src=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-14.png\" alt=\"\" class=\"wp-image-41647\" srcset=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-14.png 318w, https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-14-300x206.png 300w\" sizes=\"auto, (max-width: 318px) 100vw, 318px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Um eine neue Benachrichtigungsregel zu erstellen, klickt man einfach auf die Schaltfl\u00e4che \u201eHinzuf\u00fcgen\u201d. In der Folge \u00f6ffnet sich das unten dargestellte Fenster und Sie haben die M\u00f6glichkeit, die Konfiguration durchzuf\u00fchren.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"227\" height=\"371\" src=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-15.png\" alt=\"\" class=\"wp-image-41648\" srcset=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-15.png 227w, https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-15-184x300.png 184w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Im n\u00e4chsten Schritt ist ein Name f\u00fcr die Benachrichtigungsregel zu vergeben. Bitte w\u00e4hlen Sie anschlie\u00dfend eine der folgenden Optionen aus, um die Benutzerzuweisung zu definieren:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Private Regel<\/li>\n\n\n\n<li>Allgemeine Regel<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcber die Schaltfl\u00e4che \u201eEmpf\u00e4nger\u201d k\u00f6nnen bei der Auswahl \u201eAllgemeine Regel\u201d diese genauer spezifiziert und eingegrenzt werden.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"209\" height=\"233\" src=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-16.png\" alt=\"\" class=\"wp-image-41649\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"210\" height=\"234\" src=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-17.png\" alt=\"\" class=\"wp-image-41650\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Im oberen Beispiel wird f\u00fcr den Benutzer \u201eAndreas Trefzer\u201d eine Benachrichtigung versendet. An alle anderen Benutzer wird jedoch keine Benachrichtigung versendet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vordefinierte-benachrichtigungsregeln\">Vordefinierte Benachrichtigungsregeln<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um festzulegen, bei welchem Ereignis eine Benachrichtigung versendet wird, stehen zwei verschiedene Auswahlm\u00f6glichkeiten zur Verf\u00fcgung.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Beim Auftreten eines ausgew\u00e4hlten Ereignisses<\/li>\n\n\n\n<li>Wen ein Objekt den Filterbedingungen entspricht<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die einfachste und schnellste Definition ist mittels der vordefinierten Ereignisse m\u00f6glich und auch zu empfehlen, sofern diese den Anforderungen entsprechen. Bitte beachten Sie dazu die orangen Boxen im unteren Bild.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"227\" height=\"371\" src=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-18.png\" alt=\"\" class=\"wp-image-41651\" srcset=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-18.png 227w, https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-18-184x300.png 184w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-einsatz-von-filtern\">Einsatz von Filtern<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Falls die vordefinierten Ereignisse nicht ausreichen, k\u00f6nnen Sie \u00fcber die Option \u201eWenn ein Objekt den Filterbedingungen entspricht\u201d und die Schaltfl\u00e4che \u201eFilter definieren\u201d eine genaue und detaillierte Definition erstellen. Die Bildschirmfotos unten zeigen, was alles m\u00f6glich ist. So kann auf Basis der Metadaten, des Dateityps oder der Berechtigung eine genaue Filterung zum Ausl\u00f6sen einer Benachrichtigung definiert werden.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"309\" height=\"172\" src=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-21.png\" alt=\"\" class=\"wp-image-41654\" srcset=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-21.png 309w, https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-21-300x167.png 300w\" sizes=\"auto, (max-width: 309px) 100vw, 309px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"308\" height=\"171\" src=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-22.png\" alt=\"\" class=\"wp-image-41655\" srcset=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-22.png 308w, https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-22-300x167.png 300w\" sizes=\"auto, (max-width: 308px) 100vw, 308px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"306\" height=\"171\" src=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-23.png\" alt=\"\" class=\"wp-image-41656\" srcset=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-23.png 306w, https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-23-300x168.png 300w\" sizes=\"auto, (max-width: 306px) 100vw, 306px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"307\" height=\"172\" src=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-24.png\" alt=\"\" class=\"wp-image-41657\" srcset=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-24.png 307w, https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-24-300x168.png 300w\" sizes=\"auto, (max-width: 307px) 100vw, 307px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Um eine Benachrichtigung an sich selbst zu vermeiden, kann dies mit der im Bildschirmfoto unten markierten Schaltfl\u00e4che verhindert werden.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"367\" src=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-25.png\" alt=\"\" class=\"wp-image-41658\" srcset=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-25.png 222w, https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-25-181x300.png 181w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-fazit\">Fazit<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.linkedin.com\/in\/andreas-trefzer-120282b\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ich <\/a>hoffe, dass diese Anleitung hilfreich ist und als solide Grundlage dient, um M-Files-Benachrichtigungen an die individuellen Bed\u00fcrfnisse anzupassen. F\u00fcr weitere Fragen zu anderen Themen rund um die M-Files Produkte stehen <a href=\"https:\/\/www.dbi-services.com\" target=\"_blank\" rel=\"noreferrer noopener\">wir<\/a> Ihnen gerne zur Verf\u00fcgung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was sind Benachrichtigungen in M-Files In M-Files besteht die M\u00f6glichkeit, Benachrichtigungen, sogenannte Zuweisungen, auf Basis von Ereignissen zu automatisieren. Die M-Files Benutzer werden zum einen direkt in M-Files mittels Zuweisungen informiert und zum anderen per E-Mail. Derzeit wird empfohlen, die Benachrichtigungsregeln mit dem klassischen M-Files-Client zu konfigurieren, da dieser die detailliertesten Konfigurationsm\u00f6glichkeiten bietet. Benachrichtigungen erstellen [&hellip;]<\/p>\n","protected":false},"author":88,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[525],"tags":[3190],"type_dbi":[3238],"class_list":["post-41643","post","type-post","status-publish","format-standard","hentry","category-enterprise-content-management","tag-m-files","type-m-files"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Benachrichtigungen in M-Files - dbi Blog<\/title>\n<meta name=\"description\" content=\"Benachrichtigungen in M-Files\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Benachrichtigungen in M-Files\" \/>\n<meta property=\"og:description\" content=\"Benachrichtigungen in M-Files\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/\" \/>\n<meta property=\"og:site_name\" content=\"dbi Blog\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-26T13:31:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-13.png\" \/>\n\t<meta property=\"og:image:width\" content=\"451\" \/>\n\t<meta property=\"og:image:height\" content=\"216\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andreas Trefzer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Trefzer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/\"},\"author\":{\"name\":\"Andreas Trefzer\",\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/#\\\/schema\\\/person\\\/9b30a20c9bd5481ae107999c48ef66a0\"},\"headline\":\"Benachrichtigungen in M-Files\",\"datePublished\":\"2025-11-26T13:31:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/\"},\"wordCount\":407,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/image-13.png\",\"keywords\":[\"M-Files\"],\"articleSection\":[\"Enterprise content management\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/\",\"url\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/\",\"name\":\"Benachrichtigungen in M-Files - dbi Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/image-13.png\",\"datePublished\":\"2025-11-26T13:31:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/#\\\/schema\\\/person\\\/9b30a20c9bd5481ae107999c48ef66a0\"},\"description\":\"Benachrichtigungen in M-Files\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/image-13.png\",\"contentUrl\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/image-13.png\",\"width\":451,\"height\":216},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/benachrichtigungendefinition-in-m-files\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Benachrichtigungen in M-Files\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/\",\"name\":\"dbi Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/#\\\/schema\\\/person\\\/9b30a20c9bd5481ae107999c48ef66a0\",\"name\":\"Andreas Trefzer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d7c61db93ff87c7e90d105f7971c65737ff0b5eb1597d0f0a78f08c2513b1336?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d7c61db93ff87c7e90d105f7971c65737ff0b5eb1597d0f0a78f08c2513b1336?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d7c61db93ff87c7e90d105f7971c65737ff0b5eb1597d0f0a78f08c2513b1336?s=96&d=mm&r=g\",\"caption\":\"Andreas Trefzer\"},\"url\":\"https:\\\/\\\/www.dbi-services.com\\\/blog\\\/author\\\/andreastrefzer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Benachrichtigungen in M-Files - dbi Blog","description":"Benachrichtigungen in M-Files","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/","og_locale":"en_US","og_type":"article","og_title":"Benachrichtigungen in M-Files","og_description":"Benachrichtigungen in M-Files","og_url":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/","og_site_name":"dbi Blog","article_published_time":"2025-11-26T13:31:59+00:00","og_image":[{"width":451,"height":216,"url":"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-13.png","type":"image\/png"}],"author":"Andreas Trefzer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Andreas Trefzer","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/#article","isPartOf":{"@id":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/"},"author":{"name":"Andreas Trefzer","@id":"https:\/\/www.dbi-services.com\/blog\/#\/schema\/person\/9b30a20c9bd5481ae107999c48ef66a0"},"headline":"Benachrichtigungen in M-Files","datePublished":"2025-11-26T13:31:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/"},"wordCount":407,"commentCount":0,"image":{"@id":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-13.png","keywords":["M-Files"],"articleSection":["Enterprise content management"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/","url":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/","name":"Benachrichtigungen in M-Files - dbi Blog","isPartOf":{"@id":"https:\/\/www.dbi-services.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/#primaryimage"},"image":{"@id":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-13.png","datePublished":"2025-11-26T13:31:59+00:00","author":{"@id":"https:\/\/www.dbi-services.com\/blog\/#\/schema\/person\/9b30a20c9bd5481ae107999c48ef66a0"},"description":"Benachrichtigungen in M-Files","breadcrumb":{"@id":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/#primaryimage","url":"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-13.png","contentUrl":"https:\/\/www.dbi-services.com\/blog\/wp-content\/uploads\/sites\/2\/2025\/11\/image-13.png","width":451,"height":216},{"@type":"BreadcrumbList","@id":"https:\/\/www.dbi-services.com\/blog\/benachrichtigungendefinition-in-m-files\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.dbi-services.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Benachrichtigungen in M-Files"}]},{"@type":"WebSite","@id":"https:\/\/www.dbi-services.com\/blog\/#website","url":"https:\/\/www.dbi-services.com\/blog\/","name":"dbi Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dbi-services.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.dbi-services.com\/blog\/#\/schema\/person\/9b30a20c9bd5481ae107999c48ef66a0","name":"Andreas Trefzer","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d7c61db93ff87c7e90d105f7971c65737ff0b5eb1597d0f0a78f08c2513b1336?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d7c61db93ff87c7e90d105f7971c65737ff0b5eb1597d0f0a78f08c2513b1336?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d7c61db93ff87c7e90d105f7971c65737ff0b5eb1597d0f0a78f08c2513b1336?s=96&d=mm&r=g","caption":"Andreas Trefzer"},"url":"https:\/\/www.dbi-services.com\/blog\/author\/andreastrefzer\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dbi-services.com\/blog\/wp-json\/wp\/v2\/posts\/41643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dbi-services.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dbi-services.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dbi-services.com\/blog\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dbi-services.com\/blog\/wp-json\/wp\/v2\/comments?post=41643"}],"version-history":[{"count":11,"href":"https:\/\/www.dbi-services.com\/blog\/wp-json\/wp\/v2\/posts\/41643\/revisions"}],"predecessor-version":[{"id":41679,"href":"https:\/\/www.dbi-services.com\/blog\/wp-json\/wp\/v2\/posts\/41643\/revisions\/41679"}],"wp:attachment":[{"href":"https:\/\/www.dbi-services.com\/blog\/wp-json\/wp\/v2\/media?parent=41643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dbi-services.com\/blog\/wp-json\/wp\/v2\/categories?post=41643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dbi-services.com\/blog\/wp-json\/wp\/v2\/tags?post=41643"},{"taxonomy":"type","embeddable":true,"href":"https:\/\/www.dbi-services.com\/blog\/wp-json\/wp\/v2\/type_dbi?post=41643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}